{"id":2,"date":"2012-10-16T23:03:07","date_gmt":"2012-10-16T21:03:07","guid":{"rendered":"http:\/\/2012-bologna.wordcamp.org\/?page_id=2"},"modified":"2012-11-14T10:47:20","modified_gmt":"2012-11-14T08:47:20","slug":"ggdbologna","status":"publish","type":"page","link":"https:\/\/bologna.wordcamp.org\/2012\/ggdbologna\/","title":{"rendered":"Chi \u00e8 GGDBologna?"},"content":{"rendered":"<p><strong><\/p>\n<p style=\"text-align: left\">Girl Geek Dinners Bologna \u00e8 una associazione di promozione sociale che promuove internet come driver di democrazia, libert\u00e0 e cultura. Organizziamo iniziative di formazione per promuovere l&#8217; alfabetizzazione digitale dei cittadini. Lavoriamo stretta collaborazione con le Istituzioni sul nostro territorio per facilitare le iniziative atte a combattere il digital divide, per promuovere l&#8217;inclusione digitale e spingere Internet come strumento di emancipazione per le donne. Incoraggiamo eventi, riunioni e conferenze per cercare di coinvolgere le donne con la tecnologia e nuovi media.<br \/>\nStiamo collaborando con l&#8217; agenda digitale della citt\u00e0 di Bologna.<\/p>\n<p><\/strong><\/p>\n<p style=\"text-align: left\">Girl Geek Dinners Bologna is a no-profit association. We promote internet as democracy, freedom and culture driver. We Organize training initiatives to bring digital alphabetization to citizen. We work close with instiutions on our territory to facilitate initiatives to fight the digital divide, to promote the digital inclusion and to push internet as a emancipation tool for women.We encourage events, meeting and conference to try to involve women with technology and new media.We are doing a close job with the local DAE of the city of Bologna.<\/p>\n<p style=\"text-align: left\">Le <a href=\"http:\/\/girlgeekdinners.com\/\"><strong>Girl Geek Dinners<\/strong><\/a> (o GGD) nascono <a href=\"http:\/\/girlgeekdinners.com\/?page_id=10\">da un\u2019idea<\/a> di <a href=\"http:\/\/sarahblow.com\/\">Sarah Blow<\/a>.<\/p>\n<p style=\"text-align: left\">Le <strong>GGD<\/strong> sono cene o incontri destinate a <strong>donne <\/strong>appassionate di <strong>tecnologia<\/strong>, <strong>Internet <\/strong>e <strong>nuovi media<\/strong>. Sono delle opportunit\u00e0 speciali per incontrare e socializzare con donne interessanti durante una cena. Vengono <strong>organizzate in tutto il mondo<\/strong> e sono eventi unici e assolutamente divertenti.<\/p>\n<p style=\"text-align: left\">Sono cene senza scopro di lucro e organizzate da un gruppo di volontarie.<\/p>\n<p style=\"text-align: left\">Lo <strong>scopo<\/strong> di queste cene \u00e8 far conoscere e unire le donne che lavorano in questo settore, quello dell\u2019hi-tech, trasformandolo in una comunit\u00e0, in cui chiaramente anche gli uomini sono benvenuti. La speranza \u00e8 di vedere questi incontri moltiplicarsi in giro per il mondo.<\/p>\n<p style=\"text-align: left\"><strong>Le cene sono Girls only.<\/strong><\/p>\n<p style=\"text-align: left\">In realt\u00e0, ci si incontrano anche uomini, ma ammessi a partecipare solo come invitati speciali di una donna e in numero limitato ad alcuni eventi.<\/p>\n<h3 style=\"text-align: left\">Come sono nate le GGD?<\/h3>\n<p style=\"text-align: left\">Sarah Blow, una software engineer inglese, stanca di ritrovarsi in nettissima minoranza alle conferenze tecniche e di essere scambiata per una persona del reparto marketing o qualsiasi altra cosa tranne che per un tecnico decide di organizzare una cena per donne che lavorano nell\u2019IT.<\/p>\n<p style=\"text-align: left\">Era la Londra dell\u2019agosto del 2005.<\/p>\n<h3 style=\"text-align: left\">Altre GGD nel mondo:<\/h3>\n<p style=\"text-align: left\">Inghilterra, Irlanda, Germania, Belgio, Olanda, Grecia, Canada, Nuova Zelanda, Australia, Malaysia, USA\u2026<\/p>\n<h3 style=\"text-align: left\">Altre GGD in Italia:<\/h3>\n<p style=\"text-align: left\">Milano, Roma, Firenze, Urbino, Bologna e&#8230; molte altre citt\u00e0!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Girl Geek Dinners Bologna \u00e8 una associazione di promozione sociale che promuove internet come driver di democrazia, libert\u00e0 e cultura. Organizziamo iniziative di formazione per promuovere l&#8217; alfabetizzazione digitale dei cittadini. Lavoriamo stretta collaborazione con le Istituzioni sul nostro territorio &hellip; <a href=\"https:\/\/bologna.wordcamp.org\/2012\/ggdbologna\/\">Continue reading <span class=\"screen-reader-text\">Chi \u00e8 GGDBologna?<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":10568889,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PheMYW-2","_links":{"self":[{"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/users\/10568889"}],"replies":[{"embeddable":true,"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":6,"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":258,"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/pages\/2\/revisions\/258"}],"wp:attachment":[{"href":"https:\/\/bologna.wordcamp.org\/2012\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}